{"id":1077,"date":"2023-12-12T10:08:48","date_gmt":"2023-12-12T13:08:48","guid":{"rendered":"http:\/\/abr.aero\/?p=1"},"modified":"2023-12-12T10:08:48","modified_gmt":"2023-12-12T13:08:48","slug":"os-desafios-do-setor-pela-voz-das-executivas","status":"publish","type":"post","link":"https:\/\/anm2025.abr.aero\/en\/os-desafios-do-setor-pela-voz-das-executivas\/","title":{"rendered":"Os desafios do setor pela voz das executivas"},"content":{"rendered":"<p>Composto em sua totalidade por executivas mulheres, o primeiro Painel do ANM \u201923 teve como tema o desenvolvimento do setor e seus principais desafios. Moderados por Mariana Menezes, gerente jur\u00eddica-regulat\u00f3ria da ABR, elas discutiram o panorama dos aeroportos e seus maiores desafios, em um cen\u00e1rio p\u00f3s-pandemia.<\/p>\n\n\n\n<p>Ana Benevides, chefe de Gabinete da ANAC, levantou a quest\u00e3o dos desafios da inclus\u00e3o no setor a\u00e9reo, chamando a aten\u00e7\u00e3o para a necessidade de haver um trabalho coordenado do setor voltado para a maior capacita\u00e7\u00e3o e consequente inclus\u00e3o de profissionais mulheres no mercado de trabalho do setor a\u00e9reo. Ela ressaltou ainda o Programa Asas para Todos, da ANAC, que visa a fomentar a diversidade, equidade e inclus\u00e3o para passageiros e profissionais na avia\u00e7\u00e3o civil.<\/p>\n\n\n\n<p>Paola Aires, advogada e s\u00f3cia da Dutra e Associados, falou sobre a consensualidade e o desafio de acomodar os leg\u00edtimos interesses de atores envolvidos em lit\u00edgios oriundos de disputas no \u00e2mbito da gest\u00e3o contratual acumuladas em mais de 10 anos de concess\u00f5es aeroportu\u00e1rias, enalteceu a negocia\u00e7\u00e3o fora do Judici\u00e1rio, em um ambiente no qual a atmosfera e os mecanismos de media\u00e7\u00e3o s\u00e3o utilizados em favor do consenso, do acordo pelo fim da disputa, visando sempre ao interesse p\u00fablico: \u201c\u00c9 poss\u00edvel fazer acordos que s\u00e3o bons para o consumidor, concession\u00e1rias e agentes p\u00fablicos, em um ambiente de coopera\u00e7\u00e3o\u201d.<\/p>\n\n\n\n<p>Para Jaqueline Gil, diretora de Marketing Internacional, Neg\u00f3cios e Sustentabilidade da Embratur, o desafio da expans\u00e3o do turismo \u00e9 passarmos dos famosos patamares estabelecidos pelo recorde de turistas registrado em 2018, com 6,7 milh\u00f5es de estrangeiros e o recorde de entrada de divisas registrado em 2014, durante a Copa do Mundo, com US$ 6,5 bilh\u00f5es. \u201cEstamos muito aqu\u00e9m da nossa possibilidade\u201d, afirmou a executiva, falando da ambi\u00e7\u00e3o de chegarmos, em 2027, a oito milh\u00f5es de turistas e US$ 9 bilh\u00f5es em divisas. Ela salientou que, para se chegar nesses n\u00fameros, s\u00e3o necess\u00e1rios investimentos e parcerias, como a estabelecida entre a Embratur e a ABR, que visa \u00e0 valoriza\u00e7\u00e3o da imagem do Brasil no mercado do turismo internacional, prioriza\u00e7\u00e3o de destinos brasileiros e aprimoramento da experi\u00eancia do turista estrangeiro.<\/p>\n\n\n\n<p>A gerente de contas s\u00eanior da SITA, Simone Yoneshigue, abordou o desafio da implanta\u00e7\u00e3o da tecnologia, um fator que se desenvolveu fortemente por conta da pandemia, com uma s\u00e9rie de solu\u00e7\u00f5es biom\u00e9tricas e digitaliza\u00e7\u00e3o de processos. \u201cTecnologia n\u00e3o \u00e9 o desafio, \u00e9 a solu\u00e7\u00e3o. Desafio \u00e9 a converg\u00eancia de agendas entre os v\u00e1rios stakeholders: aeroportos, empresas a\u00e9reas e governos. \u00c9 alinhar interesses, prioridades, timing e suporte financeiro\u201d, disse.<\/p>\n\n\n\n<p>Jurema Monteiro, presidente da Abear, falou do desafio da converg\u00eancia entre os diversos stakeholders do setor. Ela ressalta que 2023 se consolidou como a volta da vontade de viajar pelos brasileiros, mas que ainda h\u00e1 muito por fazer, como enfrentar o aumento de custos do setor e a descontinuidade de alguns segmentos que impactam na cadeia produtiva onerando todo o processo. Indicando como maior desafio a atra\u00e7\u00e3o de novos passageiros, Jurema destacou que \u201ca palavra \u00e9 converg\u00eancia, esfor\u00e7o cooperado, a\u00e7\u00f5es conjuntas, construindo uma agenda com diferentes atores: governo, Congresso e os parceiros privados, como a ABR\u201d.<\/p>","protected":false},"excerpt":{"rendered":"<p>Em um painel composto s\u00f3 por lideran\u00e7as femininas, discutiu-se o panorama do setor e os principais<\/p>","protected":false},"author":1,"featured_media":1081,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_joinchat":[],"footnotes":""},"categories":[9,10],"tags":[],"class_list":["post-1077","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-airportnews","category-anm"],"_links":{"self":[{"href":"https:\/\/anm2025.abr.aero\/en\/wp-json\/wp\/v2\/posts\/1077","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/anm2025.abr.aero\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/anm2025.abr.aero\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/anm2025.abr.aero\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/anm2025.abr.aero\/en\/wp-json\/wp\/v2\/comments?post=1077"}],"version-history":[{"count":0,"href":"https:\/\/anm2025.abr.aero\/en\/wp-json\/wp\/v2\/posts\/1077\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/anm2025.abr.aero\/en\/wp-json\/wp\/v2\/media\/1081"}],"wp:attachment":[{"href":"https:\/\/anm2025.abr.aero\/en\/wp-json\/wp\/v2\/media?parent=1077"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/anm2025.abr.aero\/en\/wp-json\/wp\/v2\/categories?post=1077"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/anm2025.abr.aero\/en\/wp-json\/wp\/v2\/tags?post=1077"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}