{"id":3422,"date":"2024-11-07T09:46:07","date_gmt":"2024-11-07T12:46:07","guid":{"rendered":"https:\/\/abr.aero\/?p=3422"},"modified":"2024-11-07T09:46:07","modified_gmt":"2024-11-07T12:46:07","slug":"ii-encontro-anual-dos-comites-tecnicos-da-abr-reune-recorde-de-publico-e-promove-debate-para-as-acoes-aeroportuarias","status":"publish","type":"post","link":"https:\/\/anm2025.abr.aero\/en\/ii-encontro-anual-dos-comites-tecnicos-da-abr-reune-recorde-de-publico-e-promove-debate-para-as-acoes-aeroportuarias\/","title":{"rendered":"II Encontro Anual dos Comit\u00eas T\u00e9cnicos da ABR re\u00fane recorde de p\u00fablico e promove debate para as a\u00e7\u00f5es aeroportu\u00e1rias"},"content":{"rendered":"<p><\/p>\n\n\n\n<p>O II Encontro Anual dos Comit\u00eas T\u00e9cnicos da ABR Aeroportos do Brasil, que aconteceu nesta segunda-feira (4), superou as expectativas e bateu recorde, com a participa\u00e7\u00e3o de 80 representantes das 13 associadas da entidade. Considerado um sucesso, o evento tem como objetivo fomentar a troca de experi\u00eancias e promover um di\u00e1logo integrado sobre os principais desafios e prioridades para o pr\u00f3ximo ano.<\/p>\n\n\n\n<p>Os participantes foram divididos em quatro grupos, de acordo com suas \u00e1reas de atua\u00e7\u00e3o, e participaram de din\u00e2micas e oficinas que permitiram o compartilhamento de realidades operacionais e a discuss\u00e3o de temas estrat\u00e9gicos para 2025. O Comit\u00ea Jur\u00eddico-Regulat\u00f3rio, coordenado pelo CEO F\u00e1bio Rog\u00e9rio Carvalho, trouxe discuss\u00f5es sobre a integra\u00e7\u00e3o da estrat\u00e9gia jur\u00eddica e regulat\u00f3ria com a estrat\u00e9gia empresarial, media\u00e7\u00e3o de conflitos e temas essenciais para o avan\u00e7o da avia\u00e7\u00e3o brasileira. As oficinas tiveram temas musicais a fim de tornar o trabalho mais din\u00e2mico.<\/p>\n\n\n\n<p>O Comit\u00ea de Opera\u00e7\u00f5es e Cargas, liderado pelo diretor executivo da ABR Aeroportos do Brasil, Tiago Bonvini, explorou o cotidiano das \u00e1reas de opera\u00e7\u00f5es dos aeroportos e as perspectivas de aprimoramento. Entre os temas discutidos estiveram Seguran\u00e7a da Avia\u00e7\u00e3o Civil (AVSEC)- apresentado pela ANAC, moderniza\u00e7\u00e3o de equipamentos de inspe\u00e7\u00e3o, poss\u00edveis solu\u00e7\u00f5es para Aircraft Recovery, e o ajustes em normativos de bombeiros com suas respectivas implica\u00e7\u00f5es em recursos humanos, elabora\u00e7\u00e3o do indicador de desempenho das ESATAS e utiliza\u00e7\u00e3o de Drones para monitoramento do s\u00edtio aeroportu\u00e1rio.<\/p>\n\n\n\n<p>No Comit\u00ea de Comunica\u00e7\u00e3o, conduzido pela assessora Cec\u00edlia Melo, foram abordados desafios enfrentados pelas assessorias de comunica\u00e7\u00e3o, incluindo campanhas institucionais, inspe\u00e7\u00f5es aleat\u00f3rias, implementa\u00e7\u00e3o de salas multissensoriais e a jornada do passageiro. A equipe discutiu ainda temas priorit\u00e1rios e tend\u00eancias em comunica\u00e7\u00e3o e branding para 2025. Al\u00e9m disso, a equipe comercial da ABR contou com o apoio da Embratur, que mediou parte das discuss\u00f5es.<\/p>\n\n\n\n<p>J\u00e1 o time de desenvolvimento de rotas, contou com a participa\u00e7\u00e3o de gestores da Embratur e promoveu discuss\u00f5es a respeito de estrat\u00e9gias conjuntas para o desenvolvimento do turismo dom\u00e9stico e internacional.<\/p>\n\n\n\n<p>Para o CEO F\u00e1bio Rog\u00e9rio, a grande ades\u00e3o \u00e9 sin\u00f4nimo do quanto o trabalho tem ganhado destaque e relev\u00e2ncia para as associadas e comemorou o sucesso. \u201cAo encerrarmos o primeiro dia do ANM, o evento interno do ANM com intenso trabalho dos comit\u00eas. Um dia bastante produtivo, em que discutimos muitos projetos, com os nossos comit\u00eas jur\u00eddico-regulat\u00f3rio, opera\u00e7\u00f5es de cargas, unifica\u00e7\u00f5es, com o nosso time de desenvolvimento de rotas. O momento tamb\u00e9m em que foi poss\u00edvel dividir um pouco as nossas experi\u00eancias num ambiente leve e produtivo.\u201d, explicou.<\/p>\n\n\n\n<p>Para a Renata Oliveira, gerente jur\u00eddica da Vinci Airports, a experi\u00eancia foi enriquecedora e afirmou ter grande interesse em participar de outras edi\u00e7\u00f5es. \u201cO evento foi incr\u00edvel, queria agradecer a ABR. Foram muitas trocas durante o dia. Estou esperando ansiosamente pelo nosso pr\u00f3ximo encontro\u201d, afirmou.<\/p>","protected":false},"excerpt":{"rendered":"<p>O II Encontro Anual dos Comit\u00eas T\u00e9cnicos da ABR Aeroportos do Brasil, que aconteceu nesta segunda-feira (4), superou as expectativas e bateu recorde, com a participa\u00e7\u00e3o de 80 representantes das 13 associadas da entidade. Considerado um sucesso, o evento tem como objetivo fomentar a troca de experi\u00eancias e promover um di\u00e1logo integrado sobre os principais [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":3423,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_joinchat":[],"footnotes":""},"categories":[9],"tags":[],"class_list":["post-3422","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-airportnews"],"_links":{"self":[{"href":"https:\/\/anm2025.abr.aero\/en\/wp-json\/wp\/v2\/posts\/3422","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/anm2025.abr.aero\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/anm2025.abr.aero\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/anm2025.abr.aero\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/anm2025.abr.aero\/en\/wp-json\/wp\/v2\/comments?post=3422"}],"version-history":[{"count":0,"href":"https:\/\/anm2025.abr.aero\/en\/wp-json\/wp\/v2\/posts\/3422\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/anm2025.abr.aero\/en\/wp-json\/wp\/v2\/media\/3423"}],"wp:attachment":[{"href":"https:\/\/anm2025.abr.aero\/en\/wp-json\/wp\/v2\/media?parent=3422"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/anm2025.abr.aero\/en\/wp-json\/wp\/v2\/categories?post=3422"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/anm2025.abr.aero\/en\/wp-json\/wp\/v2\/tags?post=3422"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}