{"id":3444,"date":"2024-11-08T11:00:00","date_gmt":"2024-11-08T14:00:00","guid":{"rendered":"https:\/\/abr.aero\/?p=3444"},"modified":"2024-11-08T11:00:00","modified_gmt":"2024-11-08T14:00:00","slug":"com-foco-em-esg-e-tecnologia-anm-2024-aposta-em-publico-qualificado-e-debate-desafios-e-perspectivas-sob-a-otica-de-acoes-concretas-para-o-setor-aeroportuario-brasileiro","status":"publish","type":"post","link":"https:\/\/anm2025.abr.aero\/en\/com-foco-em-esg-e-tecnologia-anm-2024-aposta-em-publico-qualificado-e-debate-desafios-e-perspectivas-sob-a-otica-de-acoes-concretas-para-o-setor-aeroportuario-brasileiro\/","title":{"rendered":"Com foco em ESG e tecnologia, ANM 2024 aposta em p\u00fablico qualificado e debate desafios e perspectivas, sob \u00e0 \u00f3tica de a\u00e7\u00f5es concretas, para o setor aeroportu\u00e1rio brasileiro"},"content":{"rendered":"<p><em>Em sua 4\u00aa edi\u00e7\u00e3o, o evento reuniu mais de 400 participantes, com p\u00fablico predominante de l\u00edderes do setor aeroportu\u00e1rio, \u00f3rg\u00e3o regulador e autoridades p\u00fablicas<\/em><\/p>\n\n\n\n<p>Da vis\u00e3o para a a\u00e7\u00e3o. Foi com esse prop\u00f3sito que o Airport National Meeeting 2024 norteou a programa\u00e7\u00e3o desta edi\u00e7\u00e3o. Em seu quarto ano consecutivo, o evento reuniu atores-chave e tomadores de decis\u00e3o do setor aeroportu\u00e1rio brasileiro e mundial. Com mais de 400 participantes, entre eles autoridades do poder p\u00fablico, de ag\u00eancias reguladoras, especialistas e executivos do setor privado, a cerim\u00f4nia demonstrou as a\u00e7\u00f5es que v\u00eam sendo implementadas pelos aeroportos no que tange a Agenda ESG (social, ambiental e governan\u00e7a) e a tecnologia, sobretudo aplicada \u00e0 experi\u00eancia do passageiro.<\/p>\n\n\n\n<p>Em seu discurso de abertura, o CEO da ABR Aeroportos do Brasil, F\u00e1bio Rog\u00e9rio Carvalho, enfatizou os desafios enfrentados pelo setor neste ano e as perspectivas de futuro da avia\u00e7\u00e3o no cen\u00e1rio nacional e internacional. \u201cMuito mais do que vis\u00e3o e palavras\u2026 a\u00e7\u00f5es! N\u00f3s somos o setor que transformou e continua a transformar, em definitivo, a forma como os brasileiros viajam de avi\u00e3o. N\u00f3s somos os aeroportos do Brasil. O nosso ANM ganhou uma proje\u00e7\u00e3o e import\u00e2ncia que muito nos alegra, um espa\u00e7o de troca essencial para o encontro da ind\u00fastria e do setor p\u00fablico com os aeroportos. A avia\u00e7\u00e3o \u00e9 um universo de opera\u00e7\u00f5es di\u00e1rias complexas em que minutos fazem diferen\u00e7a, e nos aeroportos do Brasil, essas atividades s\u00e3o sempre desempenhadas pelos nossos times com seguran\u00e7a e efici\u00eancia\u201d, destacou Carvalho em sua fala.<\/p>\n\n\n\n<p>Sob o tema Aeroportos e Futuro Sustent\u00e1vel: da vis\u00e3o para a a\u00e7\u00e3o, o ANM 2024 apresentou quatro pain\u00e9is de debates concentrados em: agenda ESG e pol\u00edticas p\u00fablicas; governan\u00e7a; tecnologia e a jornada do passageiro e mudan\u00e7as clim\u00e1ticas e infraestrutura.<\/p>\n\n\n\n<p>Estiveram presentes no evento o ministro de Portos e Aeroportos, Silvio Costa Filho; a secret\u00e1ria-executiva do Minist\u00e9rio, Mariana Pescatori; o secret\u00e1rio nacional de Avia\u00e7\u00e3o Civil, Tom\u00e9 Franca; o comandante do Sexto Comando A\u00e9reo Regional da For\u00e7a A\u00e9rea Brasileira (Comaer), Major Brigadeiro do Ar Jefferson Darolt; o diretor-presidente substituto da Ag\u00eancia Nacional de Avia\u00e7\u00e3o Civil (ANAC), Ricardo Catanant; a diretora substituta da ANAC, Mariana Alto\u00e9; os CEOs das 13 concession\u00e1rias aeroportu\u00e1rias, associadas da ABR; dirigentes e representantes da Associa\u00e7\u00e3o Latino-Americana e do Caribe de Transporte A\u00e9reo (Alta), da Associa\u00e7\u00e3o Internacional de Transporte A\u00e9reo&nbsp;(IATA), do Conselho Internacional de Aeroportos da Am\u00e9rica Latina e Caribe (ACI-LAC), da Associa\u00e7\u00e3o Brasileira das Empresas A\u00e9reas (Abear), al\u00e9m da deputada Iza Arruda (MDB \u2013 PE) e outras autoridades. Os debates ao longo da programa\u00e7\u00e3o foram liderados por relevantes especialistas do setor, que facilitaram discuss\u00f5es entre autoridades e profissionais de destaque.<\/p>\n\n\n\n<p><strong>Coopera\u00e7\u00e3o para o desenvolvimento<\/strong><\/p>\n\n\n\n<p>Marcado por lan\u00e7amentos e assinaturas direcionados ao fortalecimento e aprimoramento do setor, o ANM destacou a import\u00e2ncia de acordos de coopera\u00e7\u00e3o para o crescimento inovador, inclusivo, eficiente e seguro dos aeroportos. Durante a solenidade de abertura, no contexto social, foi assinada a ades\u00e3o ao Programa de Acolhimento ao Passageiro com Transtorno do Espectro Autista. O programa visa proporcionar uma melhor experi\u00eancia nos aeroportos brasileiros para passageiros neurodivergentes, especialmente aqueles com TEA, e seus familiares.<\/p>\n\n\n\n<p>No campo acad\u00eamico, a ABR firmou um acordo de coopera\u00e7\u00e3o com a universidade aeron\u00e1utica Embry-riddle. A coopera\u00e7\u00e3o tem como objetivo viabilizar capacita\u00e7\u00e3o internacional da comunidade aeroportu\u00e1ria brasileira com oferta de curso especialmente desenvolvido para o aprimoramento de profissionais em alto n\u00edvel de excel\u00eancia.<\/p>\n\n\n\n<p>Por fim, as associa\u00e7\u00f5es do setor de Avia\u00e7\u00e3o Civil se uniram para formalizar propostas ao Poder P\u00fablico, delineando as prioridades para a moderniza\u00e7\u00e3o da avia\u00e7\u00e3o civil brasileira. A Carta de Bras\u00edlia, documento assinado pelas entidades, elenca as medidas que a ind\u00fastria identifica como essenciais e necess\u00e1rias para o desenvolvimento sustent\u00e1vel, competitivo e seguro da avia\u00e7\u00e3o e dos aeroportos no Brasil.<\/p>\n\n\n\n<p>Confira a \u00edntegra do ANM 2024 clicando <a href=\"https:\/\/www.youtube.com\/watch?v=MzK9h497uj4&amp;t=19908s\" data-type=\"link\" data-id=\"https:\/\/www.youtube.com\/watch?v=MzK9h497uj4&amp;t=19908s\" target=\"_blank\" rel=\"noopener\">aqui<\/a><\/p>","protected":false},"excerpt":{"rendered":"<p>Em sua 4\u00aa edi\u00e7\u00e3o, o evento reuniu mais de 400 participantes, com p\u00fablico predominante de l\u00edderes do setor aeroportu\u00e1rio, \u00f3rg\u00e3o regulador e autoridades p\u00fablicas Da vis\u00e3o para a a\u00e7\u00e3o. Foi com esse prop\u00f3sito que o Airport National Meeeting 2024 norteou a programa\u00e7\u00e3o desta edi\u00e7\u00e3o. Em seu quarto ano consecutivo, o evento reuniu atores-chave e tomadores [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":3445,"comment_status":"closed","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"_joinchat":[],"footnotes":""},"categories":[9],"tags":[],"class_list":["post-3444","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-airportnews"],"_links":{"self":[{"href":"https:\/\/anm2025.abr.aero\/en\/wp-json\/wp\/v2\/posts\/3444","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/anm2025.abr.aero\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/anm2025.abr.aero\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/anm2025.abr.aero\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/anm2025.abr.aero\/en\/wp-json\/wp\/v2\/comments?post=3444"}],"version-history":[{"count":0,"href":"https:\/\/anm2025.abr.aero\/en\/wp-json\/wp\/v2\/posts\/3444\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/anm2025.abr.aero\/en\/wp-json\/wp\/v2\/media\/3445"}],"wp:attachment":[{"href":"https:\/\/anm2025.abr.aero\/en\/wp-json\/wp\/v2\/media?parent=3444"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/anm2025.abr.aero\/en\/wp-json\/wp\/v2\/categories?post=3444"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/anm2025.abr.aero\/en\/wp-json\/wp\/v2\/tags?post=3444"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}