{"id":3434,"date":"2024-11-08T12:06:03","date_gmt":"2024-11-08T15:06:03","guid":{"rendered":"https:\/\/abr.aero\/?p=3434"},"modified":"2024-11-08T12:06:03","modified_gmt":"2024-11-08T15:06:03","slug":"integridade-em-foco-a-importancia-da-governanca-para-o-desenvolvimento-dos-aeroportos","status":"publish","type":"post","link":"https:\/\/anm2025.abr.aero\/es\/integridade-em-foco-a-importancia-da-governanca-para-o-desenvolvimento-dos-aeroportos\/","title":{"rendered":"Integridade em Foco: A Import\u00e2ncia da Governan\u00e7a para o desenvolvimento dos Aeroportos"},"content":{"rendered":"<p><\/p>\n\n\n\n<p>O Painel 2 do ANM 2024, intitulado &#8220;Governan\u00e7a Corporativa: O valor da transpar\u00eancia e da integridade nos neg\u00f3cios aeroportu\u00e1rios&#8221;, reuniu l\u00edderes do setor para discutir a import\u00e2ncia de pr\u00e1ticas \u00e9ticas e transparentes na gest\u00e3o aeroportu\u00e1ria. Moderado por Constan\u00e7a Daher, diretora de Infraestrutura e Projetos de Capital da A&amp;M Infra, o painel contou com a participa\u00e7\u00e3o de Ana Maria Rovai, diretora Jur\u00eddica da CCR Aeroportos; Santiago Yus, diretor-presidente da Aena Brasil; Jorge Arruda, CEO da Inframerica; Roberta Negr\u00e3o, advogada e consultora em regula\u00e7\u00e3o da Dutra e Associados Advocacia e Silvio Caracas, secret\u00e1rio-adjunto de Controle Externo do Tribunal de Contas da Uni\u00e3o (TCU).<\/p>\n\n\n\n<p>Durante as discuss\u00f5es, os participantes enfatizaram que a governan\u00e7a corporativa s\u00f3lida \u00e9 fundamental para a sustentabilidade e o sucesso dos neg\u00f3cios aeroportu\u00e1rios.<\/p>\n\n\n\n<p>Quest\u00f5es como a import\u00e2ncia da transpar\u00eancia nas opera\u00e7\u00f5es para o fortalecimento da confian\u00e7a dos investidores e usu\u00e1rios, a integridade nas pr\u00e1ticas de gest\u00e3o como elemento essencial para a reputa\u00e7\u00e3o das empresas no mercado global, al\u00e9m da ado\u00e7\u00e3o de pol\u00edticas de compliance que contribuem para mitiga\u00e7\u00e3o de riscos e para a efici\u00eancia operacional, garantindo credibilidade das organiza\u00e7\u00f5es, foram o centro das reflex\u00f5es abordadas.<\/p>\n\n\n\n<p>A troca de experi\u00eancias e perspectivas entre os participantes evidenciou que a governan\u00e7a corporativa eficaz \u00e9 um diferencial estrat\u00e9gico no setor aeroportu\u00e1rio. A ado\u00e7\u00e3o de pr\u00e1ticas que promovam a transpar\u00eancia e a integridade n\u00e3o apenas satisfaz as expectativas dos stakeholders, mas tamb\u00e9m fortalece o ambiente de neg\u00f3cios.<\/p>\n\n\n\n<p>Confira a \u00edntegra do ANM 2024 clicando <a href=\"https:\/\/www.youtube.com\/watch?v=MzK9h497uj4\" data-type=\"link\" data-id=\"https:\/\/www.youtube.com\/watch?v=MzK9h497uj4\" target=\"_blank\" rel=\"noopener\">aqui<\/a><\/p>\n\n\n\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>O Painel 2 do ANM 2024, intitulado &#8220;Governan\u00e7a Corporativa: O valor da transpar\u00eancia e da integridade nos neg\u00f3cios aeroportu\u00e1rios&#8221;, reuniu l\u00edderes do setor para discutir a import\u00e2ncia de pr\u00e1ticas \u00e9ticas e transparentes na gest\u00e3o aeroportu\u00e1ria. Moderado por Constan\u00e7a Daher, diretora de Infraestrutura e Projetos de Capital da A&amp;M Infra, o painel contou com a participa\u00e7\u00e3o [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":3435,"comment_status":"closed","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"_joinchat":[],"footnotes":""},"categories":[9],"tags":[],"class_list":["post-3434","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-airportnews"],"_links":{"self":[{"href":"https:\/\/anm2025.abr.aero\/es\/wp-json\/wp\/v2\/posts\/3434","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/anm2025.abr.aero\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/anm2025.abr.aero\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/anm2025.abr.aero\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/anm2025.abr.aero\/es\/wp-json\/wp\/v2\/comments?post=3434"}],"version-history":[{"count":0,"href":"https:\/\/anm2025.abr.aero\/es\/wp-json\/wp\/v2\/posts\/3434\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/anm2025.abr.aero\/es\/wp-json\/wp\/v2\/media\/3435"}],"wp:attachment":[{"href":"https:\/\/anm2025.abr.aero\/es\/wp-json\/wp\/v2\/media?parent=3434"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/anm2025.abr.aero\/es\/wp-json\/wp\/v2\/categories?post=3434"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/anm2025.abr.aero\/es\/wp-json\/wp\/v2\/tags?post=3434"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}